{"id":186,"count":4,"description":"","link":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/","name":"Bags and Accessories","slug":"bags-and-accessories","taxonomy":"product_cat","parent":185,"meta":[],"menu_order":15,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bags and Accessories Archivi - Firenze Musei Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bags and Accessories Archivi - Firenze Musei Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/\" \/>\n<meta property=\"og:site_name\" content=\"Firenze Musei Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/product-category\\\/apparel\\\/bags-and-accessories\\\/\",\"url\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/product-category\\\/apparel\\\/bags-and-accessories\\\/\",\"name\":\"Bags and Accessories Archivi - Firenze Musei Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/product-category\\\/apparel\\\/bags-and-accessories\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/product-category\\\/apparel\\\/bags-and-accessories\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apparel\",\"item\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/product-category\\\/apparel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bags and Accessories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/\",\"name\":\"Firenze Musei Store\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/#organization\",\"name\":\"Firenze Musei Store\",\"url\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/FM_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/FM_logo.png\",\"width\":478,\"height\":142,\"caption\":\"Firenze Musei Store\"},\"image\":{\"@id\":\"https:\\\/\\\/www.firenzemuseistore.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bags and Accessories Archivi - Firenze Musei Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/","og_locale":"en_US","og_type":"article","og_title":"Bags and Accessories Archivi - Firenze Musei Store","og_url":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/","og_site_name":"Firenze Musei Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/","url":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/","name":"Bags and Accessories Archivi - Firenze Musei Store","isPartOf":{"@id":"https:\/\/www.firenzemuseistore.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/bags-and-accessories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.firenzemuseistore.com\/en\/"},{"@type":"ListItem","position":2,"name":"Apparel","item":"https:\/\/www.firenzemuseistore.com\/en\/product-category\/apparel\/"},{"@type":"ListItem","position":3,"name":"Bags and Accessories"}]},{"@type":"WebSite","@id":"https:\/\/www.firenzemuseistore.com\/en\/#website","url":"https:\/\/www.firenzemuseistore.com\/en\/","name":"Firenze Musei Store","description":"","publisher":{"@id":"https:\/\/www.firenzemuseistore.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.firenzemuseistore.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.firenzemuseistore.com\/en\/#organization","name":"Firenze Musei Store","url":"https:\/\/www.firenzemuseistore.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.firenzemuseistore.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.firenzemuseistore.com\/wp-content\/uploads\/2021\/10\/FM_logo.png","contentUrl":"https:\/\/www.firenzemuseistore.com\/wp-content\/uploads\/2021\/10\/FM_logo.png","width":478,"height":142,"caption":"Firenze Musei Store"},"image":{"@id":"https:\/\/www.firenzemuseistore.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.firenzemuseistore.com\/en\/wp-json\/wp\/v2\/product_cat\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firenzemuseistore.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.firenzemuseistore.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.firenzemuseistore.com\/en\/wp-json\/wp\/v2\/product_cat\/185"}],"wp:post_type":[{"href":"https:\/\/www.firenzemuseistore.com\/en\/wp-json\/wp\/v2\/product?product_cat=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}